{"id":41491,"date":"2015-04-20T14:34:52","date_gmt":"2015-04-20T12:34:52","guid":{"rendered":"https:\/\/ruralhomes.es\/index.php\/2015\/04\/20\/visites-gastronomiques-et-vinicoles\/"},"modified":"2015-04-20T14:34:52","modified_gmt":"2015-04-20T12:34:52","slug":"visites-gastronomiques-et-vinicoles","status":"publish","type":"post","link":"https:\/\/ruralhomes.es\/fr\/index.php\/2015\/04\/20\/visites-gastronomiques-et-vinicoles\/","title":{"rendered":"Visites gastronomiques et vinicoles"},"content":{"rendered":"<p>Les vacances, en Am\u00e9rique du Nord anglophone, d\u00e9crivent un voyage r\u00e9cr\u00e9atif, comme un court voyage d&rsquo;agr\u00e9ment, ou un voyage \u00e0 l&rsquo;\u00e9tranger.<br \/>\nLes habitants des pays du Commonwealth utilisent le terme \u00ab\u00a0holiday\u00a0\u00bb pour d\u00e9crire l&rsquo;absence du travail ainsi que pour d\u00e9crire des vacances ou un voyage.<br \/>\nLes vacances peuvent signifier rester \u00e0 la maison ou aller quelque part.<br \/>\nLes Canadiens utilisent souvent les termes \u00ab\u00a0vacances\u00a0\u00bb et \u00ab\u00a0jours f\u00e9ri\u00e9s\u00a0\u00bb de mani\u00e8re interchangeable pour d\u00e9signer un voyage loin de la maison ou une absence du travail.<br \/>\nEn Australie et au Royaume-Uni, les vacances peuvent d\u00e9signer un cong\u00e9 ou un jour f\u00e9ri\u00e9.<br \/>\nLes Vanderbilt, Rockefeller, Carnegie, Huntington et autres industriels richissimes ont construit leurs propres \u00ab\u00a0grands camps\u00a0\u00bb spectaculaires dans les Adirondacks du nord de l&rsquo;\u00c9tat de New York, o\u00f9 ils pouvaient se divertir avec leur famille dans un luxe priv\u00e9.<br \/>\nLes vacances \u00e0 l&rsquo;am\u00e9ricaine sont n\u00e9es, litt\u00e9ralement.<br \/>\nLes notables de la ville de New York ont pris l&rsquo;habitude de d\u00e9clarer qu&rsquo;ils allaient \u00ab\u00a0quitter\u00a0\u00bb leurs maisons de la ville pour leurs retraites d&rsquo;\u00e9t\u00e9 au bord du lac, et le terme \u00ab\u00a0vacation\u00a0\u00bb a remplac\u00e9 le terme britannique \u00ab\u00a0holiday\u00a0\u00bb dans le langage courant.<br \/>\nEn hongrois, le mot vak\u00e1ci\u00f3 peut d\u00e9signer \u00e0 la fois un voyage d&rsquo;agr\u00e9ment, une absence du travail officiellement accord\u00e9e (g\u00e9n\u00e9ralement pendant les mois les plus chauds) et les vacances scolaires d&rsquo;\u00e9t\u00e9 (les plus longues).<br \/>\nPour l&rsquo;absence du travail, le mot szabads\u00e1g (libert\u00e9) peut \u00eatre utilis\u00e9, \u00e9ventuellement comme betegszabads\u00e1g (libert\u00e9 en cas de maladie) lorsque la raison de l&rsquo;absence est de nature m\u00e9dicale.         <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les vacances, en Am\u00e9rique du Nord anglophone, d\u00e9crivent un voyage r\u00e9cr\u00e9atif, comme un court voyage d&rsquo;agr\u00e9ment, ou un voyage \u00e0 l&rsquo;\u00e9tranger. Les habitants des pays du Commonwealth utilisent le terme \u00ab\u00a0holiday\u00a0\u00bb pour d\u00e9crire l&rsquo;absence du travail ainsi que pour d\u00e9crire des vacances ou un voyage. Les vacances peuvent signifier rester \u00e0 la maison ou aller &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[113,123],"tags":[117,116],"class_list":["post-41491","post","type-post","status-publish","format-standard","hentry","category-idees-de-vacances","category-non-classe","tag-hospitalite","tag-idees-de-vacances"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ruralhomes.es\/fr\/index.php\/wp-json\/wp\/v2\/posts\/41491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ruralhomes.es\/fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ruralhomes.es\/fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ruralhomes.es\/fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ruralhomes.es\/fr\/index.php\/wp-json\/wp\/v2\/comments?post=41491"}],"version-history":[{"count":0,"href":"https:\/\/ruralhomes.es\/fr\/index.php\/wp-json\/wp\/v2\/posts\/41491\/revisions"}],"wp:attachment":[{"href":"https:\/\/ruralhomes.es\/fr\/index.php\/wp-json\/wp\/v2\/media?parent=41491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ruralhomes.es\/fr\/index.php\/wp-json\/wp\/v2\/categories?post=41491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ruralhomes.es\/fr\/index.php\/wp-json\/wp\/v2\/tags?post=41491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}